{"id":3183,"date":"2017-12-19T12:09:36","date_gmt":"2017-12-19T11:09:36","guid":{"rendered":"http:\/\/www.bustebiemme.it\/shopping-bag\/design-shopping-bags\/pocket-bag-shopper\/"},"modified":"2018-03-08T11:45:43","modified_gmt":"2018-03-08T10:45:43","slug":"pocket-bag-shopping-bag","status":"publish","type":"page","link":"https:\/\/www.bustebiemme.it\/en\/products\/shopping-bag\/design-shopping-bags\/pocket-bag-shopping-bag\/","title":{"rendered":"pocket bag shopping bag"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":3161,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-3183","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.bustebiemme.it\/en\/wp-json\/wp\/v2\/pages\/3183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bustebiemme.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.bustebiemme.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.bustebiemme.it\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bustebiemme.it\/en\/wp-json\/wp\/v2\/comments?post=3183"}],"version-history":[{"count":3,"href":"https:\/\/www.bustebiemme.it\/en\/wp-json\/wp\/v2\/pages\/3183\/revisions"}],"predecessor-version":[{"id":3538,"href":"https:\/\/www.bustebiemme.it\/en\/wp-json\/wp\/v2\/pages\/3183\/revisions\/3538"}],"up":[{"embeddable":true,"href":"https:\/\/www.bustebiemme.it\/en\/wp-json\/wp\/v2\/pages\/3161"}],"wp:attachment":[{"href":"https:\/\/www.bustebiemme.it\/en\/wp-json\/wp\/v2\/media?parent=3183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}